{"id":5709,"date":"2026-08-26T11:01:36","date_gmt":"2026-08-26T09:01:36","guid":{"rendered":"https:\/\/leserre.co\/it\/eventi\/\/"},"modified":"2026-08-27T11:26:32","modified_gmt":"2026-08-27T09:26:32","slug":"studi-sul-qui%ef%bf%bc","status":"publish","type":"eventi","link":"https:\/\/leserre.co\/%eventi-slug%\/studi-sul-qui%ef%bf%bc\/","title":{"rendered":"Studi sul Qui\ufffc"},"content":{"rendered":"\n<p>Studi sul Qui \u00e8 un progetto di deep mapping che mette al centro il lavoro sul campo per raccontare territori che vengono trascurati dalle narrazioni prevalenti.&nbsp;<br><br>La conferenza ripercorre sei stagioni di ricerca, raccontando come pratiche artistiche e scientifiche si siano progressivamente intrecciate in un metodo di ricerca condiviso.<br>Ci si soffermer\u00e0 anche ad analizzare e discutere in chiave critica alcune parole e azioni oggi ricorrenti in progetti su territori minori. Ci domanderemo cosa producono, quando le usiamo e su come provare a metterle in discussione.<\/p>\n\n\n\n<p>Studi sul Qui&nbsp;\u00e8 il primo progetto in Italia ad applicare sistematicamente il metodo della mappatura profonda per raccontare il presente dei territori.<br>Si concentra sui luoghi banalizzati, ignorati o raccontati con stereotipi. <br>Promuove l&#8217;osservazione del territorio e l&#8217;incontro con la cittadinanza, trasformando la ricerca sul campo in restituzioni concrete che non offrono risposte definitive, ma nascono dagli interrogativi della ricerca per moltiplicare le narrazioni e arricchire il dibattito su luoghi spesso cristallizzati da visioni stereotipate.<br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Studi sul Qui \u00e8 un progetto di deep mapping che mette al centro il lavoro sul campo per raccontare territori che vengono trascurati dalle narrazioni prevalenti.&nbsp; La conferenza ripercorre sei stagioni di ricerca, raccontando come pratiche artistiche e scientifiche si siano progressivamente intrecciate in un metodo di ricerca condiviso.Ci si soffermer\u00e0 anche ad analizzare e [&hellip;]<\/p>\n","protected":false},"featured_media":5710,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/eventi\/5709"}],"collection":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/eventi"}],"about":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/types\/eventi"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/media\/5710"}],"wp:attachment":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/media?parent=5709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}