{"id":5720,"date":"2026-08-27T11:24:57","date_gmt":"2026-08-27T09:24:57","guid":{"rendered":"https:\/\/leserre.co\/it\/eventi\/\/"},"modified":"2026-08-27T11:25:06","modified_gmt":"2026-08-27T09:25:06","slug":"angela-donghia-isolario","status":"publish","type":"eventi","link":"https:\/\/leserre.co\/%eventi-slug%\/angela-donghia-isolario\/","title":{"rendered":"Angela D&#8217;Onghia \u2013 Isolario"},"content":{"rendered":"\n<p><strong>I<\/strong>solario&nbsp;\u00e8 una rassegna di residenze artistiche che invita artiste e artisti di differenti discipline e provenienze, a sviluppare una riflessione sul paesaggio di provincia e periferia, inteso come arcipelago di presenze, tracce e apparizioni.<br>Per questa edizione, Isolario invita a riflettere sull\u2019idea di approdo come condizione fragile e transitoria, legata tanto ai movimenti umani quanto alle trasformazioni ecologiche e territoriali.<br><br>Le residenze&nbsp;che ospitiamo a Le(Serre sviluppano progetti installativi capaci di interrogare il concetto di approdo nelle sue dimensioni ambientali, simboliche e narrative: rifugi temporanei, dispositivi di orientamento, luoghi di incontro, tracce di passaggio, habitat immaginari, segnali, presenze o forme di coabitazione tra umano e non umano.<br>Le opere&nbsp;si configurano come isole temporanee capaci di attivare nuove modalit\u00e0 di osservazione, ascolto e conoscenza di un luogo e delle forme di vita che lo abitano.<\/p>\n\n\n\n<p><br>Artista in residenza: Angela D&#8217;Onghia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isolario&nbsp;\u00e8 una rassegna di residenze artistiche che invita artiste e artisti di differenti discipline e provenienze, a sviluppare una riflessione sul paesaggio di provincia e periferia, inteso come arcipelago di presenze, tracce e apparizioni.Per questa edizione, Isolario invita a riflettere sull\u2019idea di approdo come condizione fragile e transitoria, legata tanto ai movimenti umani quanto alle [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/eventi\/5720"}],"collection":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/eventi"}],"about":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/types\/eventi"}],"wp:attachment":[{"href":"https:\/\/leserre.co\/wp-json\/wp\/v2\/media?parent=5720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}